{"id":11523,"date":"2017-12-08T14:29:09","date_gmt":"2017-12-08T12:29:09","guid":{"rendered":"http:\/\/www.juristenkoffer.de\/refblog\/?p=11523"},"modified":"2017-12-08T14:29:09","modified_gmt":"2017-12-08T12:29:09","slug":"buch-top-seller-im-monat-november","status":"publish","type":"post","link":"https:\/\/www.juristenkoffer.de\/refblog\/allgemein\/buch-top-seller-im-monat-november\/","title":{"rendered":"Buch Top-Seller im Monat November"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6150 alignleft\" src=\"https:\/\/www.juristenkoffer.de\/refblog\/wp-content\/uploads\/2012\/07\/horak.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Wir m\u00f6chten Euch hier einige unserer <a href=\"http:\/\/www.referendarbuchladen.de\/top-seller.php\" target=\"_blank\">Top-Seller des Monats November<\/a> vorstellen. Denn vielleicht ist ja auch etwas f\u00fcr Euch dabei?<\/p>\n<p>Zivilrechtsstation:<br \/>\nKurpat &#8211; Das Zivilurteil<br \/>\nKaiser\/Kaiser\/Kaiser &#8211; Materielles Zivilrecht im Assessorexamen<br \/>\nAnders\/Gehle &#8211; Das Assessorexamen im Zivilrecht<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Strafrechtsstation:<br \/>\nRussack &#8211; Die Revision in der strafrechtlichen Assessorklausur<br \/>\nKaiser\/Bracker &#8211; Die Staatsanwaltsklausur im Assessorexamen<br \/>\nSchmitz &#8211; Der Aktenvortrag im Strafrecht<\/p>\n<p>Verwaltungsstation:<br \/>\nKaiser\/K\u00f6ster\/Seegm\u00fcller &#8211; Die \u00f6ffentlich-rechtliche Klausur im Assessorexamen<br \/>\nSartorius &#8211; Verfassungs- und Verwaltungsgesetze<br \/>\nKerst\/Gniechwitz &#8211; Die Assessorklausur im Verwaltungsrecht<\/p>\n<p style=\"border:1px solid; padding: 5px; margin: 2px 0px 10px 0px; line-height: 150%\">\n\t\t\t\tDie RefNews sind das Blog von Juristenkoffer.de - einem der ersten und mit weit mehr als 35.000 zufriedenen Kunden einem der gr\u00f6\u00dften Vermieter von Kommentaren in Deutschland. Bist Du bereits Rechtsreferendar, hast Dir aber noch keinen Juristenkoffer reserviert? Dann informiere Dich jetzt \u00fcber unser Angebot und <a href=\"https:\/\/www.juristenkoffer.de\/angebot.php?rel=textartikelrefnews\" target=\"_blank\">sichere Dir schnell Deine Examenskommentare<\/a>!\n\t\t\t\t<\/p>\n<p>Last but not least: Insider-Dossier &#8211; Standardfragen und -Themen in der m\u00fcndlichen Pr\u00fcfung im 2. Examen (auch als Ebook erh\u00e4ltlich)<\/p>\n<p>Ihr sucht noch ein bestimmtes Buch oder m\u00f6chtet Euch informieren, was es gerade so aktuell gibt? Dann schaut doch mal in unserem <a href=\"http:\/\/www.referendarbuchladen.de\/\" target=\"_blank\">Referendarbuchladen<\/a> vorbei!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir m\u00f6chten Euch hier einige unserer Top-Seller des Monats November vorstellen. Denn vielleicht ist ja auch etwas f\u00fcr Euch dabei? Zivilrechtsstation: Kurpat &#8211; Das Zivilurteil Kaiser\/Kaiser\/Kaiser &#8211; Materielles Zivilrecht im Assessorexamen Anders\/Gehle &#8211; Das Assessorexamen im Zivilrecht<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11523","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts\/11523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/comments?post=11523"}],"version-history":[{"count":3,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts\/11523\/revisions"}],"predecessor-version":[{"id":11526,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts\/11523\/revisions\/11526"}],"wp:attachment":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/media?parent=11523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/categories?post=11523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/tags?post=11523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}