{"id":10118,"date":"2015-06-10T14:20:19","date_gmt":"2015-06-10T12:20:19","guid":{"rendered":"http:\/\/www.juristenkoffer.de\/refblog\/?p=10118"},"modified":"2015-06-10T14:20:19","modified_gmt":"2015-06-10T12:20:19","slug":"refrave-party-der-referendare-in-berlin","status":"publish","type":"post","link":"https:\/\/www.juristenkoffer.de\/refblog\/allgemein\/refrave-party-der-referendare-in-berlin\/","title":{"rendered":"RefRave &#8211; Party der Referendare in Berlin"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10119\" src=\"https:\/\/www.juristenkoffer.de\/refblog\/wp-content\/uploads\/2015\/06\/flyer-2.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Der Personalrat der Referendar*innen im Bezirk des Kammergerichts hat die n\u00e4chste Party organisiert.\u00a0RefRave &#8211; die Party der Referendarinnen und Referendare. Am Freitag Abend (12.06.2015) im Freudenzimmer.<\/p>\n<p>Wir w\u00fcnschen allen feierw\u00fctigen Referendaren aus Berlin und Brandenburg viel Spa\u00df!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Personalrat der Referendar*innen im Bezirk des Kammergerichts hat die n\u00e4chste Party organisiert.\u00a0RefRave &#8211; die Party der Referendarinnen und Referendare. Am Freitag Abend (12.06.2015) im Freudenzimmer. Wir w\u00fcnschen allen feierw\u00fctigen Referendaren aus Berlin und Brandenburg viel Spa\u00df!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,117,118],"tags":[],"class_list":["post-10118","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-berlin","category-brandenburg"],"_links":{"self":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts\/10118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/comments?post=10118"}],"version-history":[{"count":1,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts\/10118\/revisions"}],"predecessor-version":[{"id":10120,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/posts\/10118\/revisions\/10120"}],"wp:attachment":[{"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/media?parent=10118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/categories?post=10118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juristenkoffer.de\/refblog\/wp-json\/wp\/v2\/tags?post=10118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}